{"id":7443,"date":"2024-01-08T16:00:48","date_gmt":"2024-01-08T16:00:48","guid":{"rendered":"https:\/\/www.pcimembranes.com\/?page_id=7443"},"modified":"2025-07-25T13:40:15","modified_gmt":"2025-07-25T13:40:15","slug":"modules-a-membrane-tubulaire-serie-c10","status":"publish","type":"page","link":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/","title":{"rendered":"Modules \u00e0 membrane tubulaire s\u00e9rie C10"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:260px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"787\" class=\"wp-block-cover__image-background wp-image-2795\" alt=\"\" src=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg 1400w, https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2-300x169.jpg 300w, https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2-1024x576.jpg 1024w, https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2-768x432.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-10 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-cc0055bde7d771503d9f4d1a4bdb27e6\">Modules \u00e0 membrane tubulaire s\u00e9rie C10<\/h1>\n<\/div><\/div>\n\n\n\n<!--Close-->\t\n<\/div><\/div><\/section>\n<!--Menu-->\n<div class=\"no-top-margin\">\n<div class=\"msb-sticky-bar\">\n<div class=\"container\">\n  <div class=\"row\">\n    <div class=\"col-sm text-center\">\n      <a href=\"https:\/\/www.pcimembranes.com\/contactus\/\" class=\"btn btn-primary solution-trigger\">PARLER A UN EXPERT<\/a>\n    <\/div>\n  <\/div>\n<\/div>\n<\/div>\n<\/div>\n<!--Open-->\n<section class=\"container\"><div class=\"row\"><div class=\"col-md-12\">\n\n\n\n<h2 class=\"wp-block-heading\">Modules \u00e0 membrane tubulaire s\u00e9rie C10<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Economic Option for Tubular Membranes<\/h3>\n\n\n\n<p>Le module C10 permet une utilisation \u00e9conomique d\u2019une large gamme de membranes tubulaires UF et NF \u00e9prouv\u00e9es et \u00e9largit la gamme de modules tubulaires de PCI. Le module a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour le traitement de l\u2019eau dans les applications municipales.<\/p>\n\n\n\n<p>La conception permet l\u2019utilisation de membranes tubulaires dans des zones o\u00f9 elles \u00e9taient auparavant consid\u00e9r\u00e9es comme non comp\u00e9titives par rapport aux configurations de membranes \u00e0 canal mince.<\/p>\n\n\n\n<p>Le module C10 est fourni comme partie d&rsquo;un \u00a0\u00bbstack\u00a0\u00bb qui comprend un cadre de support, des collecteurs et des connecteurs de module. Notre gamme de tailles et de conceptions de stacks standards peut r\u00e9pondre \u00e0 une vari\u00e9t\u00e9 de t\u00e2ches et de types d\u2019eau brute diff\u00e9rents. Alternativement, les stacks peuvent \u00eatre con\u00e7ues sp\u00e9cifiquement pour r\u00e9pondre aux besoins des applications individuelles.<\/p>\n\n\n\n<p>Le module peut \u00eatre utilis\u00e9 dans des syst\u00e8mes con\u00e7us pour fonctionner jusqu\u2019\u00e0 12 bars \u00e0 20 \u00b0C, en fonction du type de membrane install\u00e9e. Le module est disponible en standard en longueurs de 3.66 m, 1.8m et 0.9 m, offrant des surfaces de membrane de 10.5 m<sup>2<\/sup>, 5.2 m<sup>2<\/sup> et 2.6 m<sup>2<\/sup> respectivement.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Construction en ABS \u2013 l\u00e9g\u00e8re et robuste<\/li>\n\n\n\n<li>Raccordements simples des collecteurs \u2013 maintenance facile de l\u2019installation, temps d\u2019arr\u00eat r\u00e9duits<\/li>\n\n\n\n<li>Conception tubulaire \u00e0 canal ouvert \u2013 pr\u00e9filtration minimale de l\u2019alimentation requise ; convient pour des niveaux \u00e9lev\u00e9s de collo\u00efdes et de solides en suspension<\/li>\n\n\n\n<li>Nettoyage avec billes en mousse pour certaines applications \u2013 r\u00e9duction de la supervision de l\u2019op\u00e9rateur, r\u00e9duction de la consommation de produits chimiques \u00e0 seulement 4 fois par an<\/li>\n\n\n\n<li>Conception compacte des modules \u2013 construction rapide et facile de l\u2019installation<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"354\" src=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/C10_series_2_small.jpg\" alt=\"\" class=\"wp-image-592\" srcset=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/C10_series_2_small.jpg 500w, https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/C10_series_2_small-300x212.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"260\" src=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/C10_Series_Drawing_2.jpg\" alt=\"\" class=\"wp-image-594\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-aed626a3-6c28-4318-9b72-5499ad506d60\" href=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/PCI_C10_Series.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">INFORMATIONS SUR LES PRODUITS DE LA S\u00c9RIE C10 <\/a><a href=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/PCI_C10_Series.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-aed626a3-6c28-4318-9b72-5499ad506d60\">TELECHARGER<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-ca6b8f82-8075-4646-8c66-add8ade643ea\" href=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/C10-Module-Data-Sheet.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FICHE TECHNIQUE MODULE C10<\/a><a href=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/10\/C10-Module-Data-Sheet.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ca6b8f82-8075-4646-8c66-add8ade643ea\">TELECHARGER<\/a><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>PARLER A UN EXPERT Modules \u00e0 membrane tubulaire s\u00e9rie C10 Economic Option for Tubular Membranes Le module C10 permet une utilisation \u00e9conomique d\u2019une large gamme de membranes tubulaires UF et NF \u00e9prouv\u00e9es et \u00e9largit la gamme de modules tubulaires de PCI. Le module a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour le traitement de l\u2019eau dans les applications municipales. [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-7443","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modules \u00e0 membrane tubulaire s\u00e9rie C10 - PCI Membranes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modules \u00e0 membrane tubulaire s\u00e9rie C10 - PCI Membranes\" \/>\n<meta property=\"og:description\" content=\"PARLER A UN EXPERT Modules \u00e0 membrane tubulaire s\u00e9rie C10 Economic Option for Tubular Membranes Le module C10 permet une utilisation \u00e9conomique d\u2019une large gamme de membranes tubulaires UF et NF \u00e9prouv\u00e9es et \u00e9largit la gamme de modules tubulaires de PCI. Le module a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour le traitement de l\u2019eau dans les applications municipales. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/\" \/>\n<meta property=\"og:site_name\" content=\"PCI Membranes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-25T13:40:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/\",\"url\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/\",\"name\":\"Modules \u00e0 membrane tubulaire s\u00e9rie C10 - PCI Membranes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pcimembranes.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MicrosoftTeams-image-_2.jpg\",\"datePublished\":\"2024-01-08T16:00:48+00:00\",\"dateModified\":\"2025-07-25T13:40:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pcimembranes.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MicrosoftTeams-image-_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pcimembranes.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MicrosoftTeams-image-_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/modules-a-membrane-tubulaire-serie-c10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modules \u00e0 membrane tubulaire s\u00e9rie C10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/\",\"name\":\"PCI Membranes\",\"description\":\"Making the World Safer, Healthier and More Productive\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/#organization\",\"name\":\"Filtration Group\",\"url\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pcimembranes.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/FGC-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.pcimembranes.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/FGC-logo-1.png\",\"width\":1104,\"height\":224,\"caption\":\"Filtration Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pcimembranes.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modules \u00e0 membrane tubulaire s\u00e9rie C10 - PCI Membranes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/","og_locale":"fr_FR","og_type":"article","og_title":"Modules \u00e0 membrane tubulaire s\u00e9rie C10 - PCI Membranes","og_description":"PARLER A UN EXPERT Modules \u00e0 membrane tubulaire s\u00e9rie C10 Economic Option for Tubular Membranes Le module C10 permet une utilisation \u00e9conomique d\u2019une large gamme de membranes tubulaires UF et NF \u00e9prouv\u00e9es et \u00e9largit la gamme de modules tubulaires de PCI. Le module a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour le traitement de l\u2019eau dans les applications municipales. [&hellip;]","og_url":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/","og_site_name":"PCI Membranes","article_modified_time":"2025-07-25T13:40:15+00:00","og_image":[{"width":1400,"height":787,"url":"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/","url":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/","name":"Modules \u00e0 membrane tubulaire s\u00e9rie C10 - PCI Membranes","isPartOf":{"@id":"https:\/\/www.pcimembranes.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/#primaryimage"},"image":{"@id":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg","datePublished":"2024-01-08T16:00:48+00:00","dateModified":"2025-07-25T13:40:15+00:00","breadcrumb":{"@id":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/#primaryimage","url":"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg","contentUrl":"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2021\/08\/MicrosoftTeams-image-_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pcimembranes.com\/fr\/modules-a-membrane-tubulaire-serie-c10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.pcimembranes.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Modules \u00e0 membrane tubulaire s\u00e9rie C10"}]},{"@type":"WebSite","@id":"https:\/\/www.pcimembranes.com\/fr\/#website","url":"https:\/\/www.pcimembranes.com\/fr\/","name":"PCI Membranes","description":"Making the World Safer, Healthier and More Productive","publisher":{"@id":"https:\/\/www.pcimembranes.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pcimembranes.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.pcimembranes.com\/fr\/#organization","name":"Filtration Group","url":"https:\/\/www.pcimembranes.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pcimembranes.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/06\/FGC-logo-1.png","contentUrl":"https:\/\/www.pcimembranes.com\/wp-content\/uploads\/2019\/06\/FGC-logo-1.png","width":1104,"height":224,"caption":"Filtration Group"},"image":{"@id":"https:\/\/www.pcimembranes.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/pages\/7443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/comments?post=7443"}],"version-history":[{"count":0,"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/pages\/7443\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pcimembranes.com\/fr\/wp-json\/wp\/v2\/media?parent=7443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}